{"id":224,"count":7,"description":"","link":"https:\/\/easyoriginal.com\/en\/sprache\/english-starter-sets\/","name":"English - Starter-Sets","slug":"english-starter-sets","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>English - Starter-Sets Archive - EasyOriginal.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/easyoriginal.com\/en\/sprache\/english-starter-sets\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"English - Starter-Sets Archive - EasyOriginal.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/easyoriginal.com\/en\/sprache\/english-starter-sets\/\" \/>\n<meta property=\"og:site_name\" content=\"EasyOriginal.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/easyoriginal.com\\\/sprache\\\/english-starter-sets\\\/\",\"url\":\"https:\\\/\\\/easyoriginal.com\\\/sprache\\\/english-starter-sets\\\/\",\"name\":\"English - Starter-Sets Archive - EasyOriginal.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/easyoriginal.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/easyoriginal.com\\\/sprache\\\/english-starter-sets\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/easyoriginal.com\\\/sprache\\\/english-starter-sets\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/easyoriginal.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"English - Starter-Sets\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/easyoriginal.com\\\/#website\",\"url\":\"https:\\\/\\\/easyoriginal.com\\\/\",\"name\":\"EasyOriginal.com\",\"description\":\"Spa\u00df am Lesen im Original - Innovative Lesemethode f\u00fcr Fremdsprachen\",\"publisher\":{\"@id\":\"https:\\\/\\\/easyoriginal.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/easyoriginal.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/easyoriginal.com\\\/#organization\",\"name\":\"EasyOriginal Verlag\",\"url\":\"https:\\\/\\\/easyoriginal.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/easyoriginal.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/easyoriginal.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/logo_main.png\",\"contentUrl\":\"https:\\\/\\\/easyoriginal.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/logo_main.png\",\"width\":500,\"height\":103,\"caption\":\"EasyOriginal Verlag\"},\"image\":{\"@id\":\"https:\\\/\\\/easyoriginal.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"English - Starter-Sets Archive - EasyOriginal.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/easyoriginal.com\/en\/sprache\/english-starter-sets\/","og_locale":"en_GB","og_type":"article","og_title":"English - Starter-Sets Archive - EasyOriginal.com","og_url":"https:\/\/easyoriginal.com\/en\/sprache\/english-starter-sets\/","og_site_name":"EasyOriginal.com","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/easyoriginal.com\/sprache\/english-starter-sets\/","url":"https:\/\/easyoriginal.com\/sprache\/english-starter-sets\/","name":"English - Starter-Sets Archive - EasyOriginal.com","isPartOf":{"@id":"https:\/\/easyoriginal.com\/#website"},"breadcrumb":{"@id":"https:\/\/easyoriginal.com\/sprache\/english-starter-sets\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/easyoriginal.com\/sprache\/english-starter-sets\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/easyoriginal.com\/"},{"@type":"ListItem","position":2,"name":"English - Starter-Sets"}]},{"@type":"WebSite","@id":"https:\/\/easyoriginal.com\/#website","url":"https:\/\/easyoriginal.com\/","name":"EasyOriginal.com","description":"Spa\u00df am Lesen im Original - Innovative Lesemethode f\u00fcr Fremdsprachen","publisher":{"@id":"https:\/\/easyoriginal.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/easyoriginal.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/easyoriginal.com\/#organization","name":"EasyOriginal Verlag","url":"https:\/\/easyoriginal.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/easyoriginal.com\/#\/schema\/logo\/image\/","url":"https:\/\/easyoriginal.com\/wp-content\/uploads\/2020\/08\/logo_main.png","contentUrl":"https:\/\/easyoriginal.com\/wp-content\/uploads\/2020\/08\/logo_main.png","width":500,"height":103,"caption":"EasyOriginal Verlag"},"image":{"@id":"https:\/\/easyoriginal.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/easyoriginal.com\/en\/wp-json\/wp\/v2\/product_cat\/224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/easyoriginal.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/easyoriginal.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/easyoriginal.com\/en\/wp-json\/wp\/v2\/product?product_cat=224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}